{"id":20461,"date":"2026-05-11T18:56:10","date_gmt":"2026-05-11T21:56:10","guid":{"rendered":"https:\/\/sjcbancarios.com.br\/site\/?p=20461"},"modified":"2026-05-12T18:58:42","modified_gmt":"2026-05-12T21:58:42","slug":"coe-cobra-itau-reconhece-falhas-e-diz-ter-corrigido-ferramenta-de-controle-e-producao-do-gera","status":"publish","type":"post","link":"https:\/\/sjcbancarios.com.br\/site\/noticias\/coe-cobra-itau-reconhece-falhas-e-diz-ter-corrigido-ferramenta-de-controle-e-producao-do-gera\/","title":{"rendered":"COE cobra, Ita\u00fa reconhece falhas e diz ter corrigido ferramenta de controle e produ\u00e7\u00e3o do Gera."},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Ap\u00f3s cobran\u00e7as da Comiss\u00e3o de Organiza\u00e7\u00e3o dos Empregados (COE), o Ita\u00fa reconheceu falhas no sistema do Gera e informou ter conclu\u00eddo, no primeiro trimestre deste ano, atualiza\u00e7\u00f5es para corrigir problemas relatados pelos banc\u00e1rios.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O tema foi discutido em reuni\u00e3o realizada nesta ter\u00e7a-feira (28\/04) entre o banco e a representa\u00e7\u00e3o dos trabalhadores.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Entre os problemas no Gera estavam falhas no sistema de contesta\u00e7\u00e3o de metas, desaparecimento de produ\u00e7\u00f5es registradas e excesso de controles paralelos nas ag\u00eancias.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">\u201cO Ita\u00fa apresentou durante a reuni\u00e3o a nova superintendente do Gera, Gabriela Vassoler, que abordou as demandas recorrentes dos trabalhadores e as mudan\u00e7as em andamento. Foi importante o banco reconhecer que os apontamentos dos banc\u00e1rios e apresentar corre\u00e7\u00f5es\u201d, avalia Daniele Miyachiro, integrante da COE.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Outra reclama\u00e7\u00e3o discutida foi a meta trimestral sem ajuste pr\u00e9vio em casos de f\u00e9rias e afastamentos. Segundo o banco, as metas s\u00e3o recalculadas ao final de cada m\u00eas quando h\u00e1 ocorr\u00eancia desses eventos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A COE tamb\u00e9m cobrou solu\u00e7\u00e3o para situa\u00e7\u00f5es envolvendo atendimento de clientes em condi\u00e7\u00e3o de vulnerabilidade, que demandam mais tempo dos gerentes sem reflexo na produ\u00e7\u00e3o. Sobre esse ponto, o Ita\u00fa afirmou que esses clientes n\u00e3o entram na composi\u00e7\u00e3o das metas, seguindo normas do Banco Central que restringem a oferta de determinados produtos a esse p\u00fablico.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">\u201cSeguiremos acompanhando para garantir que essas mudan\u00e7as sejam percebidas na pr\u00e1tica pelos trabalhadores. Por isso \u00e9 importante que o banc\u00e1rio nos procure, sempre que necess\u00e1rio\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Outras demandas<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">A COE tamb\u00e9m debateu mudan\u00e7as no modelo de avalia\u00e7\u00e3o Evolui. A retirada dos consultores de Recursos Humanos do processo havia gerado preocupa\u00e7\u00e3o entre os trabalhadores. O Ita\u00fa esclareceu que esses profissionais continuam participando em duas etapas: na an\u00e1lise pr\u00e9via dos indicadores e na valida\u00e7\u00e3o final das decis\u00f5es tomadas pelos gestores, regionais e superintendentes.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Durante a reuni\u00e3o, o banco ainda apresentou atualiza\u00e7\u00f5es sobre compromissos do Acordo Macro de 2025. O Ita\u00fa informou que passar\u00e1 a apresentar periodicamente os dados de horas extras realizadas aos s\u00e1bados e domingos em reuni\u00f5es bimestrais.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O banco tamb\u00e9m confirmou que a plataforma de cursos IU Conecta est\u00e1 dispon\u00edvel aos empregados e que comunicados das entidades sindicais podem ser enviados aos e-mails corporativos. Outro tema tratado foi o Programa Recomece, que prev\u00ea redu\u00e7\u00e3o de metas para banc\u00e1rios afastados pelo INSS por mais de 120 dias. A representa\u00e7\u00e3o sindical cobrou o cumprimento da medida.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Ao final da reuni\u00e3o, ficou encaminhada uma nova rodada de negocia\u00e7\u00f5es para discutir banco de horas e remunera\u00e7\u00e3o vari\u00e1vel no segmento Empresas. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">(Com informa\u00e7\u00f5es Contraf)<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"excerpt\">Ap\u00f3s cobran\u00e7as da Comiss\u00e3o de Organiza\u00e7\u00e3o dos Empregados (COE), o Ita\u00fa reconheceu falhas no sistema do Gera e informou ter conclu\u00eddo, no primeiro trimestre deste ano, atualiza\u00e7\u00f5es para corrigir problemas relatados pelos banc\u00e1rios. O tema foi discutido em reuni\u00e3o realizada nesta ter\u00e7a-feira (28\/04) entre o banco e a representa\u00e7\u00e3o dos trabalhadores. Entre os problemas no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20462,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-20461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/posts\/20461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/comments?post=20461"}],"version-history":[{"count":1,"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/posts\/20461\/revisions"}],"predecessor-version":[{"id":20463,"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/posts\/20461\/revisions\/20463"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/media\/20462"}],"wp:attachment":[{"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/media?parent=20461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/categories?post=20461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/tags?post=20461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}