{"id":20458,"date":"2026-05-12T17:48:32","date_gmt":"2026-05-12T20:48:32","guid":{"rendered":"https:\/\/sjcbancarios.com.br\/site\/?p=20458"},"modified":"2026-05-12T18:53:47","modified_gmt":"2026-05-12T21:53:47","slug":"conferencia-interestadual-da-feeb-sp-ms-aprovam-eixos-da-campanha-salarial-2026","status":"publish","type":"post","link":"https:\/\/sjcbancarios.com.br\/site\/noticias\/conferencia-interestadual-da-feeb-sp-ms-aprovam-eixos-da-campanha-salarial-2026\/","title":{"rendered":"Confer\u00eancia Interestadual da Feeb SP\/MS aprovam eixos da Campanha Salarial 2026."},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><em>Encontro realizado em Ara\u00e7atuba reuniu mais de 200 delegados sindicais de S\u00e3o Paulo e Mato Grosso do Sul para debater pautas da categoria banc\u00e1ria<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">O evento contou com representantes de 21 regi\u00f5es dos estados de S\u00e3o Paulo e Mato Grosso do Sul. Durante os dois dias de atividades, dirigentes sindicais discutiram os desafios da categoria, o cen\u00e1rio pol\u00edtico e econ\u00f4mico e as principais reivindica\u00e7\u00f5es dos trabalhadores do setor.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">\u201cEste \u00e9 um ano decisivo para as banc\u00e1rias e os banc\u00e1rios, principalmente por conta da Campanha Salarial. As pautas debatidas pelos dirigentes sindicais ser\u00e3o levadas aos encontros nacionais e posteriormente apresentadas nas mesas de negocia\u00e7\u00e3o\u201d, afirmou David Zaia, presidente da Federa\u00e7\u00e3o.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">No segundo e \u00faltimo dia do encontro, representantes da Federa\u00e7\u00e3o nos bancos p\u00fablicos e privados apresentaram propostas relacionadas \u00e0s demandas da categoria. Ao final da Confer\u00eancia Interestadual, os delegados aprovaram por unanimidade os sete eixos da Campanha Salarial 2026 definidos pelo Comando Nacional dos Banc\u00e1rios:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">*aumento real dos sal\u00e1rios;<\/span><br \/>\n<span style=\"font-family: arial, helvetica, sans-serif;\">*valoriza\u00e7\u00e3o do piso da categoria;<\/span><br \/>\n<span style=\"font-family: arial, helvetica, sans-serif;\">*amplia\u00e7\u00e3o da Participa\u00e7\u00e3o nos Lucros e Resultados (PLR);<\/span><br \/>\n<span style=\"font-family: arial, helvetica, sans-serif;\">*sa\u00fade, bem-estar e combate ao adoecimento;<\/span><br \/>\n<span style=\"font-family: arial, helvetica, sans-serif;\">*defesa do emprego diante das novas tecnologias;<\/span><br \/>\n<span style=\"font-family: arial, helvetica, sans-serif;\">*defesa de um sistema financeiro mais justo e regulado;<\/span><br \/>\n<span style=\"font-family: arial, helvetica, sans-serif;\">*import\u00e2ncia das elei\u00e7\u00f5es de 2026 para a classe trabalhadora.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Tamb\u00e9m foi aprovada uma mo\u00e7\u00e3o de apoio ao presidente Luiz In\u00e1cio Lula da Silva. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">As propostas aprovadas durante a Confer\u00eancia ser\u00e3o encaminhadas ao debate nacional da categoria, programado para ocorrer entre os dias 19 e 21 de junho.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Fonte: Federa\u00e7\u00e3o dos banc\u00e1rios de SPMS<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"excerpt\">Encontro realizado em Ara\u00e7atuba reuniu mais de 200 delegados sindicais de S\u00e3o Paulo e Mato Grosso do Sul para debater pautas da categoria banc\u00e1ria O evento contou com representantes de 21 regi\u00f5es dos estados de S\u00e3o Paulo e Mato Grosso do Sul. Durante os dois dias de atividades, dirigentes sindicais discutiram os desafios da categoria, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20459,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-20458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/posts\/20458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/comments?post=20458"}],"version-history":[{"count":1,"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/posts\/20458\/revisions"}],"predecessor-version":[{"id":20460,"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/posts\/20458\/revisions\/20460"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/media\/20459"}],"wp:attachment":[{"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/media?parent=20458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/categories?post=20458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sjcbancarios.com.br\/site\/wp-json\/wp\/v2\/tags?post=20458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}